{"id":13150,"date":"2019-07-08T16:15:22","date_gmt":"2019-07-08T16:15:22","guid":{"rendered":"http:\/\/www.delinleedelovely.com\/blog\/?p=13150"},"modified":"2019-07-08T16:15:22","modified_gmt":"2019-07-08T16:15:22","slug":"obsession-1983-by-vikky-alexander","status":"publish","type":"post","link":"http:\/\/www.delinleedelovely.com\/blog\/2019\/07\/obsession-1983-by-vikky-alexander\/","title":{"rendered":"obsession (1983) by vikky alexander&#8230;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-13151\" src=\"http:\/\/www.delinleedelovely.com\/blog\/wp-content\/uploads\/2019\/07\/d58bd4fc-5414-414c-bd3c-be1b615afb7a.png\" alt=\"d58bd4fc-5414-414c-bd3c-be1b615afb7a\" width=\"626\" height=\"942\" srcset=\"http:\/\/www.delinleedelovely.com\/blog\/wp-content\/uploads\/2019\/07\/d58bd4fc-5414-414c-bd3c-be1b615afb7a.png 626w, http:\/\/www.delinleedelovely.com\/blog\/wp-content\/uploads\/2019\/07\/d58bd4fc-5414-414c-bd3c-be1b615afb7a-199x300.png 199w, http:\/\/www.delinleedelovely.com\/blog\/wp-content\/uploads\/2019\/07\/d58bd4fc-5414-414c-bd3c-be1b615afb7a-624x939.png 624w\" sizes=\"(max-width: 626px) 100vw, 626px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/posts\/13150"}],"collection":[{"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/comments?post=13150"}],"version-history":[{"count":1,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/posts\/13150\/revisions"}],"predecessor-version":[{"id":13152,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/posts\/13150\/revisions\/13152"}],"wp:attachment":[{"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/media?parent=13150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/categories?post=13150"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/tags?post=13150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}