{"id":6694,"date":"2014-05-21T03:59:46","date_gmt":"2014-05-21T03:59:46","guid":{"rendered":"http:\/\/www.delinleedelovely.com\/blog\/?p=6694"},"modified":"2014-05-21T03:59:46","modified_gmt":"2014-05-21T03:59:46","slug":"inspired-by-harris-epaminonda-collages","status":"publish","type":"post","link":"http:\/\/www.delinleedelovely.com\/blog\/2014\/05\/inspired-by-harris-epaminonda-collages\/","title":{"rendered":"inspired by: harris epaminonda collages&#8230;"},"content":{"rendered":"<p><a href=\"http:\/\/www.delinleedelovely.com\/blog\/wp-content\/uploads\/2014\/05\/IMG_3899.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-6696\" alt=\"IMG_3899\" src=\"http:\/\/www.delinleedelovely.com\/blog\/wp-content\/uploads\/2014\/05\/IMG_3899.jpg\" width=\"4000\" height=\"3000\" srcset=\"http:\/\/www.delinleedelovely.com\/blog\/wp-content\/uploads\/2014\/05\/IMG_3899.jpg 4000w, http:\/\/www.delinleedelovely.com\/blog\/wp-content\/uploads\/2014\/05\/IMG_3899-300x225.jpg 300w, http:\/\/www.delinleedelovely.com\/blog\/wp-content\/uploads\/2014\/05\/IMG_3899-1024x768.jpg 1024w, http:\/\/www.delinleedelovely.com\/blog\/wp-content\/uploads\/2014\/05\/IMG_3899-624x468.jpg 624w\" sizes=\"(max-width: 4000px) 100vw, 4000px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/posts\/6694"}],"collection":[{"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/comments?post=6694"}],"version-history":[{"count":1,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/posts\/6694\/revisions"}],"predecessor-version":[{"id":6697,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/posts\/6694\/revisions\/6697"}],"wp:attachment":[{"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/media?parent=6694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/categories?post=6694"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.delinleedelovely.com\/blog\/wp-json\/wp\/v2\/tags?post=6694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}